{"id":46,"count":2,"description":"","link":"https:\/\/iplblog.in\/index.php\/tag\/online-in-india\/","name":"Online In India?","slug":"online-in-india","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/iplblog.in\/index.php\/wp-json\/wp\/v2\/tags\/46"}],"collection":[{"href":"https:\/\/iplblog.in\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/iplblog.in\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/iplblog.in\/index.php\/wp-json\/wp\/v2\/posts?tags=46"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}